{"id":15554,"date":"2022-01-02T14:07:39","date_gmt":"2022-01-02T13:07:39","guid":{"rendered":"https:\/\/artcontest.biancoscuro.it\/site\/?p=15554"},"modified":"2022-01-02T14:07:40","modified_gmt":"2022-01-02T13:07:40","slug":"maria-lucia-albertini-2","status":"publish","type":"post","link":"https:\/\/artcontest.biancoscuro.it\/site\/maria-lucia-albertini-2\/","title":{"rendered":"Maria Lucia Albertini"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"22\" src=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1.jpg\" alt=\".......\" class=\"wp-image-1001\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1.jpg 500w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1-300x13.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Arianna nella Mitologia<br>2020<br>alluminio laccato<br>98x92x90 cm.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Arianna nella Mitologia<\/strong><br>Albertini produce questa opera tra il 2019\/2020. Toccando in modo profondo il tema che da sempre \u00e8 alla base della&nbsp; la sua poetica: il femminio o femminino come purezza di rappresentazione e \u201cri-affermazione\u201d della donna nella societ\u00e0.<br>Questa opera che si intitola \u201cArianna\u201d nella mitologia, \u00e8 un\u2019opera di grandi dimensioni, dalla prova di artista qui presentata sono in produzione e in vendita&nbsp; le successive copie in alluminio laccato. Arianna nella mitologia \u00e8 la prima di una serie di rappresentazioni femminili,&nbsp; che sono in fase di creazione. Segue in questa serie delle donne nella mitologia e il femminino, la scultura intitolata:\u201d Giuditta e Oloferne\u201d2021.<br>Questa scultura femminile come dice il titolo, si ispira e rappresenta l\u201cArianna\u201d della mitologia.<br>L\u2019Arianna di Albertini, \u00e8 colta nella posa di una donna che guarda perplessa il \u201cmondo\u201d da lontano dopo essere stata abbandonata.&nbsp; &nbsp;E\u2019 il suo sguardo sospeso e la sua bellezza classica che lasciano lo spettatore affascinato e stupito.<br>La posa naturale di Arianna seduta fa capire l\u2019intenzione di Albertini di voler dare un senso vitale alla sua scultura, che non \u00e8 una copia o un ricalco di un essere esistente, ma \u00e8 lei, \u00e8 se stessa, cio\u00e8 la rappresentazione immaginifica del femminino inteso proprio nella sua accezione filosofica profonda.&nbsp; Lo sguardo lontano dell\u2019Arianna di Albertini, colpisce perch\u00e9 \u00e8 uno sguardo che va oltre distaccandosi dalla realt\u00e0 concreta, portando lo spettatore a immaginare i suoi sogni e i pensieri innocenti traditi e il senso di solitudine e abbandono subito.<br>:<br>Arianna nella mitologia approfondimento<br>\u2026Arianna era la figlia del re di Creta, Minosse, il quale aveva imprigionato il Minotauro, mostro mezzo uomo e mezzo toro, in un labirinto costruito da Dedalo, da cui era impossibile uscire.<br>Ogni anno sette fanciulle ateniesi venivano date in pasto al mostro, finch\u00e9 Teseo, figlio del re di Atene, si nascose fra le fanciulle da sacrificare col proposito di uccidere il mostro. Arianna e Teseo si innamorarono e quando fu il turno di Teseo di entrare nel labirinto, questi dipan\u00f2 lungo il labirinto il filo regalatogli da Arianna, su suggerimento di Dedalo (il famoso filo di Arianna).Teseo uccise il Minotauro e, riavvolgendo il filo, riusc\u00ec ad uscire dal labirinto. E part\u00ec con le sue navi e Arianna. Fermatosi all\u2019isola di Nasso, dopo aver giaciuto con Arianna la abbandona sull\u2019isola deserta\u2026 poi alcune storie preseguono con Dionisio che le regala una corona&nbsp; diventa una costellazione.. (se vuoi approfondire segui e leggi sulla la mitologia di Arianna)<br><br>Perch\u00e9 Arianna nella mitologia e il femminino<br>Albertini:\u201dil nome Arianna e la mitologia che lo circonda mi hanno sempre affascinato\u2026<br>\u201cOggi pi\u00f9 che mai il mito di Arianna abbandonata da Teseo sull\u2019isola di Nasso, ci riporta al nostro tempo in cui, noi abbandonati nella nostra isola deserta, soli\u2026 vediamo il mondo allontanarsi\u2026<br>\u2026 Arianna \u00e8 un personaggio vittima del suo stesso amore e della sua stessa ingenuit\u00e0\u2026<br>Lei Arianna, che ha regalato a Teseo il filo di lana per permettergli di uscire e salvarsi dal dedalo del labirinto di Minosse da cui non sarebbe stato possibile uscire senza il suo filo, credendo nel suo amore e nella&nbsp; sua promessa di diventare sua sposa, lo segue, si imbarca con lui sulla sua nave ma viene vigliaccamente abbandonata sull\u2019isola deserta e inospitale di Nasso. Vigliaccamente e di nascosto Teseo, salpa all\u2019alba con le sue navi e fugge via abbandonandola sola sull\u2019isola deserta \u2026questo sembrerebbe il vero finale\u2026 dove Arianna guardando le navi rimane impietrita.<br>Quante Arianna ci sono nelle donne oggi, quante di noi hanno creduto nell\u2019amore e poi sono rimaste deluse. Ecco perch\u00e9 il mito di Arianna \u00e8 importante a mio parere, perch\u00e8 rappresenta la capacit\u00e0 delle donne di credere fino in fondo nell\u2019amore.<br>La storia dell\u2019arte \u00e8 ricca delle belle rappresentazioni di Arianna\u2026la bellissima principessa di Creta abbandonata sull\u2019isola di Nasso.<br>\u2026A me piace pensare anche al finale romantico in cui Dionisio si innamora di lei \u2026 e della sua bellezza e&nbsp; arrivato in suo soccorso la sposa\u2026ma questo questa \u00e8 un\u2019altra storia come il finale di una commedia del \u201cprincipe azzurro\u201d&nbsp;<br>L\u2019opera si inserisce nelle tendenze artistiche contemporanee e nelle scelte estetiche e poetiche dell\u2019artista che anche in questo imprime nelle vesti le sue impronte, ma a differenza di altre opere questa scultura \u00e8 di grandi dimensioni, quasi naturali. E si avvicina a poetiche artistiche che pur rimanendo nella corrente espressionista, esprimono la volont\u00e0 di raffigurare la realt\u00e0 in modo pi\u00f9 eloquente, avvicinando l\u2019artista ad una raffigurazione della figura umana pi\u00f9 reale.<br>Con questa opera Albertini sembra voler dare una svolta alla sua poetica, mettendosi in gioco con un immagine pi\u00f9 realistica della rappresentazione della figura umana, cos\u00ec come aveva gi\u00e0 fatto con altre opere del periodo giovanile, come il \u201d Cristo del Mantegna\u201d, \u201cla Camicia\u201d, pur mantenendo la sua inconfondibile impronta artistica nel modellato dell\u2019opera, dell\u2019abito e nella scelta dei colori.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Maria Lucia Albertini<\/strong> <em>(Novara, Italy)<\/em> Maria Lucia Albertini, in arte solo Albertini, fin da piccola ha mostrato una naturale predisposizione per la scultura. Ha iniziato la sua formazione presso il Liceo Artistico di Novara, poi la laurea in Architettura e il corso del libero Nudo presso il Brera di Milano. Oltre a operare nel settore dell\u2019architettura con successo, porta avanti ed evolve la sua originale ricerca artistica legata alla figura umana, alla luce, al segno e all\u2019impronta della materia nel tempo, rappresenta la bellezza nell\u2019et\u00e0 della giovinezza per fissarne l\u2019immortalit\u00e0.<br>Grazie al suo talento poliedrico, Albertini sperimenta e realizza, oltre ai dipinti ad olio e acrilico tra cui spiccano i particolari dipinti su lastre in ottone, sculture in: terracotta, alluminio, bronzo, resina, gesso, cera e legno. Nascono cos\u00ec la serie dei \u201cbronzi antichi\u201d dove l\u2019utilizzo del bronzo richiama il concetto di eternit\u00e0 e i conosciuti bronzi colorati, della serie \u201cbronzo organico\u201d esposti in diversi eventi e in occasione della 57\u00b0 Biennale di Venezia. Abbiamo gli affascinanti pezzi unici realizzati in legno e cera della serie \u201cbio-antropomorfa\u201d, legati al concetto ecologico dell\u2019urgente e inderogabile rispetto della natura. La serie \u201csacro e profano\u201d, dove spiccano le mani d\u2019oro innalzate, dell\u2019opera \u201cc.nineteen\u201d (2019), e le grandi sculture a dimensione naturale, Arianna,(2020), e Giuditta e Oloferne, (2021) della serie \u201cnella mitologia\u201d presentate nella V edizione di Step Art Fair di Milano nel 2021. (www.albertiniart.com) segue la critica di Liviano Papa, che ha scritto della scultura di ALBERTINI su\u00a0 Julliet numero 205 del 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Facebook<\/strong>: \/mlalbertiniart<br><strong>Facebook<\/strong>: \/albertiniart<br><strong>Instagram<\/strong>: @albertiniart<br><strong>Instagram<\/strong>: @albertiniofficial<br><strong>Web:<\/strong> www.albertiniart.com<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"21\" src=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg\" alt=\".......\" class=\"wp-image-1000\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg 500w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2-300x13.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vote for this artwork!<\/strong>&nbsp;Follow Biancoscuro Art Contest on&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/artcontest.biancoscuro\" target=\"_blank\"><strong>Facebook<\/strong><\/a>&nbsp;and&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/biancoscuroartcontest\/\" target=\"_blank\"><strong>Instagram<\/strong><\/a> then click <strong>like!<\/strong><br><strong>Vota questa opera!&nbsp;<\/strong>Segui Biancoscuro Art Contest su <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/artcontest.biancoscuro\" target=\"_blank\">Facebook<\/a>&nbsp;e <\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/biancoscuroartcontest\/\" target=\"_blank\"><strong>Instagram&nbsp;<\/strong><\/a>quindi clicca <strong>like<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><a href=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-300x300.jpg\" alt=\"opera iscritta al BIANCOSCURO Art Contest Winter Edition - un progetto a cura di BIANCOSCURO Art Magazine - 2021\" class=\"wp-image-15546\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-300x300.jpg 300w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-150x150.jpg 150w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-768x768.jpg 768w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-450x450.jpg 450w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna-600x600.jpg 600w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna.jpg 999w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Arianna nella Mitologia2020alluminio laccato98x92x90 cm. Arianna nella MitologiaAlbertini produce questa opera tra il 2019\/2020. Toccando in modo profondo il tema che da sempre \u00e8 alla base della&nbsp; la sua poetica:<a href=\"https:\/\/artcontest.biancoscuro.it\/site\/maria-lucia-albertini-2\/\">&#8230;Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":15546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15,5],"tags":[],"class_list":["post-15554","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-bac-winter-edition","category-scultura-sculpture","post_format-post-format-image"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"jetpack_featured_media_url":"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2022\/01\/albertinipresenta-Arianna.jpg","_links":{"self":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/15554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=15554"}],"version-history":[{"count":1,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/15554\/revisions"}],"predecessor-version":[{"id":15556,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/15554\/revisions\/15556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/15546"}],"wp:attachment":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=15554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=15554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=15554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}