{"id":8914,"date":"2018-12-31T16:50:00","date_gmt":"2018-12-31T14:50:00","guid":{"rendered":"https:\/\/artcontest.biancoscuro.it\/site\/?p=8914"},"modified":"2018-12-31T16:50:02","modified_gmt":"2018-12-31T14:50:02","slug":"anna-laurenti-3","status":"publish","type":"post","link":"https:\/\/artcontest.biancoscuro.it\/site\/anna-laurenti-3\/","title":{"rendered":"Anna Laurenti"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"22\" src=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1.jpg\" alt=\"linette1\" class=\"wp-image-1001\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1.jpg 500w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette1-300x13.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Impermanenza<br>60&#215;60<br>mosaico di vetro su plexiglass retroilluminato<br>2018 <br><em>Esemplificazione perfetta dell\u2019impermanenza.<br>Un continuo mutamento alla ricerca di nuovi stili ed espressioni in tutte le forme artistiche.<br>Alieno raffinato e trasgressivo, un\u2019icona senza tempo. <br>David Bowie &#8211; 1\u00b0 quadro della serie Icons<\/em><br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Anna Laurenti&nbsp; <\/strong>(<em>Pavia &#8211; Italy)<\/em> si laurea in Architettura, al Politecnico di Milano nel 1989. Nel 1991 inizia ad applicarsi, da autodidatta, alla sperimentazione delle diverse tecniche della lavorazione del vetro: piombato, tiffany, e mosaico di vetro su vetro e altri supporti. Predilige la tecnica del mosaico di vetro su vetro, soprattutto del micro mosaico, perch\u00e9 consente libert\u00e0 nel disegno, nel dimensionamento dei pezzi e contaminazioni con altri materiali, e avvia dal 1994 la creazione di pezzi unici che inserisce nei progetti che realizza. I primi lavori sono caratterizzati da disegni geometrici e floreali che riprendono gli elementi dell\u2019architettura che pi\u00f9 l\u2019appassiona: mosaici pavimentali, rosoni di cattedrali, decorazioni marocchine e liberty e che ripropone soprattutto negli elementi di arredo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 1998 partecipa alle mostre di arte\/artigianato \u201cUna coperta per l\u2019inverno\u201d e \u201cEstate\u201d al Castello di Belgioioso (PV) dove espone i suoi primi lavori. Affinata la tecnica, prosegue con la sperimentazione e attraverso la riproduzione delle opere di Van Gogh acquisisce una particolare modalit\u00e0 di taglio del vetro e le composizioni perdono la rigidit\u00e0 geometrica e diventano movimentate e libere.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dal 2002 inizia la collaborazione con il maestro legatore, Fabrizio Bertolotti, e partecipa con lui a quattro concorsi di \u201cRilegatura d\u2019arte\u201d disegnando le copertine dei libri e realizzando direttamente le parti in mosaico di vetro. Due libri ricevono un premio per la rilegatura e per l\u2019originalit\u00e0 del disegno e della composizione in vetro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2002 &#8211; II mostra internazionale di rilegatura d\u2019arte in Italia \u2013 Macerata &#8211; libro \u201cCantico delle creature\u201d selezionato fra i primi 100.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2005 &#8211; 8\u00b0 Biennale Mondiale de la Reliure d\u2019Art \u2013 \u201cLe tour de monde en 80 jours\u201d &#8211; libro premiato, prix de AXA Assurance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2007 &#8211; 9\u00b0 Biennale Mondiale de la Reliure d\u2019Art &#8211; \u201cContes de ma m\u00e8re l\u2019oye\u201d &#8211; libro premiato, prix de La Ville de Chevreuse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2008 \u2013 Esposizione \u201cQu\u00e9bec reli\u00e9e comme jamais\u201d per celebrare il 400\u00b0 anniversario della citt\u00e0 di Qu\u00e9bec. Libro selezionato \u201cRaspail \u2013 En canot sur les chemins d\u2019eau do roi\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dal 2014 lavora a una collezione di quadri in vetro denominata \u201cCome ti vedo\u201d ispirata alle \u201cbellezze\u201d caratteriali e fisiche delle persone che la circondano, convinta che alcune caratteristiche siano universali e possano emozionare. Amici e colleghi dei quali coglie e rappresenta passioni e qualit\u00e0. Familiari che ricorda o a cui vorrebbe fare regali impossibili. Un viaggio nelle emozioni, un percorso di ricerca psicologica e di virtuosismi nella tecnica e nei vetri che utilizza.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2015 espone i primi sei quadri della collezione e altri suoi lavori nel \u201cPalazzetto del Carmagnola\u201d a Casei Gerola (PV), un palazzetto privato del 1400 aperto in occasione delle giornate del FAI, raccogliendo consenso di pubblico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2016, partecipa con il quadro n\u00b0 4 (Laura) della collezione al concorso \u201cLa quadrata\u201d della galleria d\u2019arte Il melograno di Livorno. Il quadro \u00e8 fra i selezionati e resta in esposizione presso la galleria dal 24 giugno al 12 luglio 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2017 viene selezionata e partecipa al premio Artesalerno con il quadro Regalo \u2013 seconda vita e ottiene dalla Commissione di Arte Salerno composta dai critici, curatori e esperti d&#8217;arte contemporanea: Jean Blanchaert, Federico Caloi, Rosario Sprovieri, Rosita Taurone, la recensione di seguito allegata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019attivit\u00e0 artistica di Anna Laurenti si identifica con la pittura su vetro, una pittura dalle forme originali, che \u00e8 il risultato di un\u2019affascinante espressione manuale.&nbsp; L\u2019opera dell\u2019artista colpisce per la semplicit\u00e0 e per l\u2019equilibrio delle forme e dei colori. Una delle caratteristiche pi\u00f9 importanti del suo stile \u00e8 l&#8217;ispirazione alla natura, di cui studia gli elementi strutturali, traducendoli in una linea dinamica e ondulata, con tratto delicato. Possiamo scorgere nel suo linguaggio pittorico, una tenue adesione allo stile Art Nouveau: semplici figure sembrano prendere vita ed evolversi naturalmente in forme simili a piante o fiori. Anna Laurenti \u00e8 un\u2019artista d\u2019intraprendente creativit\u00e0, dotata di uno spirito fervido e brillante; Una sperimentatrice che attraverso una continua ricerca, ha raggiunto singolari livelli espressivi, sempre rielaborati, sempre personalizzati.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel 2018 viene selezionata e partecipa a:<br>\u2022&nbsp; 1\u00b0 Biennale del tirreno \u2013 tema del concorso \u201cAmore e solidariet\u00e0\u201d dove presenta il quadro \u201cPharos\u201d;<br>\u2022&nbsp; ArteMilano \u2013 tema \u201cPop revolution\u201d dove presenta il quadro \u201cImpermanenza\u201d vincendo il premio della critica per la sezione \u201ctiffany\u201d.<br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"21\" src=\"http:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg\" alt=\"linette2\" class=\"wp-image-1000\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2.jpg 500w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2015\/03\/linette2-300x13.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vote for this artwork!<\/strong>&nbsp;Follow Biancoscuro Art Contest on&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/artcontest.biancoscuro\" target=\"_blank\"><strong>Facebook<\/strong><\/a>&nbsp;and&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/biancoscuroartcontest\/\" target=\"_blank\"><strong>Instagram<\/strong><\/a> then click <strong>like!<\/strong><br><strong>Vota questa opera!&nbsp;<\/strong>Segui Biancoscuro Art Contest su <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/artcontest.biancoscuro\" target=\"_blank\">Facebook<\/a>&nbsp;e <\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/biancoscuroartcontest\/\" target=\"_blank\"><strong>Instagram&nbsp;<\/strong><\/a>quindi clicca <strong>like!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza.jpg\" alt=\"\" class=\"wp-image-8915\" srcset=\"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza.jpg 1000w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza-150x150.jpg 150w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza-300x300.jpg 300w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza-768x768.jpg 768w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza-450x450.jpg 450w, https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza-600x600.jpg 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; Impermanenza60&#215;60mosaico di vetro su plexiglass retroilluminato2018 Esemplificazione perfetta dell\u2019impermanenza.Un continuo mutamento alla ricerca di nuovi stili ed espressioni in tutte le forme artistiche.Alieno raffinato e trasgressivo, un\u2019icona senza tempo.<a href=\"https:\/\/artcontest.biancoscuro.it\/site\/anna-laurenti-3\/\">&#8230;Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":8915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[15,4],"tags":[],"class_list":["post-8914","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-bac-winter-edition","category-pittura-painting","post_format-post-format-image"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"jetpack_featured_media_url":"https:\/\/artcontest.biancoscuro.it\/site\/wp-content\/uploads\/2018\/12\/Impermanenza.jpg","_links":{"self":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/8914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/comments?post=8914"}],"version-history":[{"count":1,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/8914\/revisions"}],"predecessor-version":[{"id":8916,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/posts\/8914\/revisions\/8916"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/media\/8915"}],"wp:attachment":[{"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/media?parent=8914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/categories?post=8914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artcontest.biancoscuro.it\/site\/wp-json\/wp\/v2\/tags?post=8914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}